{"id":3,"date":"2024-02-29T01:24:10","date_gmt":"2024-02-29T04:24:10","guid":{"rendered":"https:\/\/stplaylivebr.com\/?page_id=3"},"modified":"2024-03-01T01:20:15","modified_gmt":"2024-03-01T04:20:15","slug":"politica-de-privacidade","status":"publish","type":"page","link":"https:\/\/stplaylivebr.com\/index.php\/politica-de-privacidade\/","title":{"rendered":"Pol\u00edtica de privacidade"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76fd430a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76fd430a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ec15ec\" data-id=\"9ec15ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-201d06dc elementor-widget elementor-widget-text-editor\" data-id=\"201d06dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h1 class=\"wp-block-heading\">Pol\u00edtica de Privacidade<\/h1><p><\/p><p class=\"wp-block-paragraph\"><strong>ESTA POL\u00cdTICA DE PRIVACIDADE FOI FORMULADA COM O INTUITO DE MANTER A PRIVACIDADE E A SEGURAN\u00c7A DAS INFORMA\u00c7\u00d5ES COLETADAS DE NOSSOS CLIENTES E USU\u00c1RIOS.<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>POL\u00cdTICA DE PRIVACIDADE DE WORLD 7\u00a0<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\">Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva e agrad\u00e1vel poss\u00edvel. A garantia da confidencialidade dos dados pessoais dos utilizadores do nosso site \u00e9 importante para a<strong> fectort4k .<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\">Todas as informa\u00e7\u00f5es pessoais relativas a membros, assinantes, clientes ou visitantes que usem a fectort4k<strong>\u00a0<\/strong>\u00a0ser\u00e3o tratadas em concord\u00e2ncia com a Lei da Prote\u00e7\u00e3o de Dados Pessoais de 26 de outubro de 1998 (Lei n.\u00ba 67\/98).<\/p><p><\/p><p class=\"wp-block-paragraph\">A informa\u00e7\u00e3o pessoal recolhida pode incluir o seu nome, e-mail, n\u00famero de telefone e\/ou telem\u00f3vel, morada, data de nascimento e\/ou outros.<\/p><p><\/p><p class=\"wp-block-paragraph\">O uso dafectort4k\u00a0pressup\u00f5e a aceita\u00e7\u00e3o deste Acordo de privacidade. A equipa da\u00a0<strong>Connect Hdtv\u00a0<\/strong>\u00a0reserva-se ao direito de alterar este acordo sem aviso pr\u00e9vio. Deste modo, recomendamos que consulte esta p\u00e1gina com regularidade de forma a estar sempre atualizado.<\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>OS AN\u00daNCIOS<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\">Tal como outros websites, coletamos e utilizamos informa\u00e7\u00e3o contida nos an\u00fancios. A informa\u00e7\u00e3o contida nos an\u00fancios, inclui o seu endere\u00e7o IP (Internet Protocol), o seu ISP (Internet Service Provider, como o Sapo, Clix, ou outro), o browser que utilizou ao visitar o nosso website (como o Internet Explorer ou o Firefox), o tempo da sua visita e que p\u00e1ginas visitou dentro do nosso website.<\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>OS COOKIES E WEB BEACONS<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\">Utilizamos cookies para armazenar informa\u00e7\u00e3o, tais como as suas prefer\u00eancias pessoas quando visita o nosso website. Isto poder\u00e1 incluir um simples popup, ou uma liga\u00e7\u00e3o em v\u00e1rios servi\u00e7os que providenciamos, tais como f\u00f3runs.<\/p><p><\/p><p class=\"wp-block-paragraph\">Em adi\u00e7\u00e3o tamb\u00e9m utilizamos publicidade de terceiros no nosso website para suportar os custos de manuten\u00e7\u00e3o. Alguns destes publicit\u00e1rios, poder\u00e3o utilizar tecnologias como os cookies e\/ou web beacons quando publicitam no nosso website, o que far\u00e1 com que esses publicit\u00e1rios (como o Google atrav\u00e9s do Google AdSense) tamb\u00e9m recebam a sua informa\u00e7\u00e3o pessoal, como o endere\u00e7o IP, o seu ISP, o seu browser, etc. Esta fun\u00e7\u00e3o \u00e9 geralmente utilizada para geotargeting (mostrar publicidade de Lisboa apenas aos leitores oriundos de Lisboa por ex.) ou apresentar publicidade direcionada a um tipo de utilizador (como mostrar publicidade de restaurante a um utilizador que visita sites de culin\u00e1ria regularmente, por ex.).<\/p><p><\/p><p class=\"wp-block-paragraph\">Voc\u00ea det\u00e9m o poder de desligar os seus cookies, nas op\u00e7\u00f5es do seu browser, ou efetuando altera\u00e7\u00f5es nas ferramentas de programas Anti-Virus, como o Norton Internet Security. No entanto, isso poder\u00e1 alterar a forma como interage com o nosso website, ou outros websites. Isso poder\u00e1 afetar ou n\u00e3o permitir que fa\u00e7a logins em programas, sites ou f\u00f3runs da nossa e de outras redes.<\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>LIGA\u00c7\u00d5ES A SITES DE TERCEIROS<\/strong><\/p><p><\/p><p class=\"wp-block-paragraph\"><strong>A fectort4k <\/strong>possui liga\u00e7\u00f5es para outros sites, os quais, a nosso ver, podem conter informa\u00e7\u00f5es \/ ferramentas \u00fateis para os nossos visitantes. A nossa pol\u00edtica de privacidade n\u00e3o \u00e9 aplicada a sites de terceiros, pelo que, caso visite outro site a partir do nosso dever\u00e1 ler a politica de privacidade do mesmo.<\/p><p><\/p><p class=\"wp-block-paragraph\">N\u00e3o nos responsabilizamos pela pol\u00edtica de privacidade ou conte\u00fado presente nesses mesmos sites.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidade ESTA POL\u00cdTICA DE PRIVACIDADE FOI FORMULADA COM O INTUITO DE MANTER A PRIVACIDADE E A SEGURAN\u00c7A DAS INFORMA\u00c7\u00d5ES COLETADAS DE NOSSOS CLIENTES E USU\u00c1RIOS. POL\u00cdTICA DE PRIVACIDADE DE WORLD 7\u00a0 Todas as suas informa\u00e7\u00f5es pessoais recolhidas, ser\u00e3o usadas para o ajudar a tornar a sua visita no nosso site o mais produtiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":120,"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/120"}],"wp:attachment":[{"href":"https:\/\/stplaylivebr.com\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}